{"id":15054,"date":"2026-04-23T09:46:02","date_gmt":"2026-04-23T08:46:02","guid":{"rendered":"https:\/\/rightcom.com\/?post_type=rightcom_jobs&#038;p=15054"},"modified":"2026-05-03T21:07:48","modified_gmt":"2026-05-03T20:07:48","slug":"controleur-financier","status":"publish","type":"rightcom_jobs","link":"https:\/\/rightcom.com\/fr\/careers\/job\/controleur-financier\/","title":{"rendered":"Contr\u00f4leur Financier"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><strong>A propos du poste<\/strong><\/h5>\n\n\n\n<p>Depuis plus de dix ans, RightCom r\u00e9volutionne l\u2019exp\u00e9rience client en Afrique. En cr\u00e9ant des exp\u00e9riences innovantes qui rendent le parcours client fluide, personnalis\u00e9, simple et exceptionnel, RightCom permet aux entreprises dans une trentaine de pays de prosp\u00e9rer dans l\u2019\u00e9conomie de l\u2019exp\u00e9rience.<\/p>\n\n\n\n<p>Notre plateforme CX, RightCom XP, permet aux entreprises d\u2019anticiper les besoins de leurs clients et d\u2019identifier les opportunit\u00e9s de vente additionnelle et crois\u00e9e sur tous les points de contact (application mobile, site web, point de vente, centre de contact et r\u00e9seau d\u2019agents), tandis que RightCom OS fournit des services manag\u00e9s de nouvelle g\u00e9n\u00e9ration.<\/p>\n\n\n\n<p>Nos convictions sont au c\u0153ur de notre activit\u00e9. Chaque jour, nous puisons notre inspiration dans nos valeurs fondamentales&nbsp;: cr\u00e9ativit\u00e9, confiance et succ\u00e8s client. Ensemble, ces valeurs nous permettent de travailler comme une seule et m\u00eame \u00e9quipe globale, en pla\u00e7ant nos clients au centre de toutes nos actions. Elles nous incitent \u00e9galement \u00e0 prendre soin de nous-m\u00eames, des autres et de nos communaut\u00e9s.<\/p>\n\n\n\n<p>Nous sommes engag\u00e9s dans un programme d\u2019innovation visant \u00e0 transformer les comp\u00e9tences humaines et technologiques de l\u2019ensemble de l\u2019organisation afin de proposer une offre digitale pour chaque produit et service. Notre ambition est de mettre en \u0153uvre des points de donn\u00e9es et des solutions digitales qui nous permettent d\u2019attirer, de fid\u00e9liser et d\u2019accro\u00eetre notre client\u00e8le.<\/p>\n\n\n\n<p>Le Contr\u00f4leur Financier reporte au Chief Financial Officer et a pour mission de :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Garantir de la fiabilit\u00e9 des informations comptables et financi\u00e8res de la soci\u00e9t\u00e9<\/li>\n\n\n\n<li>Accompagner la Direction G\u00e9n\u00e9rale et les Directions op\u00e9rationnelles dans le suivi et l&rsquo;optimisation des activit\u00e9s<\/li>\n\n\n\n<li>Analyser la sant\u00e9 financi\u00e8re et am\u00e9liorer la rentabilit\u00e9 de l\u2019entreprise<\/li>\n\n\n\n<li>Assurer et contr\u00f4ler la production et la r\u00e9gularit\u00e9 du reporting \u00e0 destination du groupe<\/li>\n\n\n\n<li>Impl\u00e9menter la d\u00e9clinaison op\u00e9rationnelle, la r\u00e9partition et l\u2019application de l\u2019ensemble des projets initi\u00e9s par la Direction financi\u00e8re groupe<\/li>\n\n\n\n<li>Aider \u00e0 la mise en place des dispositifs de contr\u00f4le interne et de gestion des risques<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Responsabilit\u00e9s<\/strong><\/h5>\n\n\n\n<p>Vous intervenez dans un contexte de d\u00e9veloppement des activit\u00e9s et prenez en charge le contr\u00f4le de gestion et le contr\u00f4le interne\u00a0:<\/p>\n\n\n\n<p><strong>Pilotage de gestion<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Animer le processus budg\u00e9taire et \u00e9laborer les pr\u00e9visions avec l&rsquo;ensemble des op\u00e9rationnels,<\/li>\n\n\n\n<li>Endosser un r\u00f4le de \u00ab Business Partner \u00bb des diff\u00e9rentes \u00e9quipes afin de les accompagner dans l&rsquo;\u00e9laboration et la r\u00e9alisation de leur strat\u00e9gie de d\u00e9veloppement,<\/li>\n\n\n\n<li>Participer activement \u00e0 la mise en place et \u00e0 l&rsquo;optimisation des outils de gestion (d\u00e9clinaison de la comptabilit\u00e9 analytique, d\u00e9finitions des indicateurs clefs de performance, \u00e9laboration des rapports d&rsquo;activit\u00e9, proposition d&rsquo;outils d&rsquo;aide \u00e0 la prise de d\u00e9cision),<\/li>\n\n\n\n<li>\u00c9laborer les rapports d&rsquo;activit\u00e9 \u00e0 destination de la DG et des documents n\u00e9cessaires \u00e0 la pr\u00e9paration et \u00e0 la tenue des conseils d\u2019administrations et assembl\u00e9es g\u00e9n\u00e9rales<\/li>\n\n\n\n<li>Participer \u00e0 l&rsquo;organisation g\u00e9n\u00e9rale de l&rsquo;entreprise<\/li>\n<\/ul>\n\n\n\n<p><strong>Am\u00e9lioration des performances de l\u2019entreprise<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Assurer les reportings mensuels (P&amp;L, Bilan, Cash Flow)<\/li>\n\n\n\n<li>Anticiper les d\u00e9rives, mener des actions correctrices<\/li>\n\n\n\n<li>Contr\u00f4ler que ces actions correctrices aient bien les effets escompt\u00e9s<\/li>\n\n\n\n<li>D\u00e9terminer les zones d&rsquo;optimisation et aider les responsables op\u00e9rationnels \u00e0 r\u00e9aliser des \u00e9conomies<\/li>\n\n\n\n<li>Mener toute \u00e9tude sp\u00e9cifique \u00e0 la demande de la Direction<\/li>\n<\/ul>\n\n\n\n<p><strong>&nbsp;&nbsp; Contr\u00f4le interne<\/strong><strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Veillez au respect des proc\u00e9dures internes et \u00e0 la fiabilisation des informations<\/li>\n\n\n\n<li>Etre force de proposition pour l\u2019am\u00e9lioration des r\u00e8gles et proc\u00e9dures<\/li>\n\n\n\n<li>Etre le garant de la sauvegarde des actifs de la soci\u00e9t\u00e9<\/li>\n\n\n\n<li>Etc<\/li>\n<\/ul>\n\n\n\n<p>&nbsp;&nbsp;&nbsp; <strong>Gestion des risques<\/strong><strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Participer \u00e0 la cartographie et l\u2019\u00e9valuation des risques<\/li>\n\n\n\n<li>Participer \u00e0 l\u2019\u00e9laboration des plans d&rsquo;actions pr\u00e9ventives et des plans de continuit\u00e9 d&rsquo;activit\u00e9<\/li>\n\n\n\n<li>Mettre en place le suivi des risques<\/li>\n\n\n\n<li>\u00catre force proposition de solution de transfert de risques \u00e0 tiers,<\/li>\n\n\n\n<li>Etc<\/li>\n<\/ul>\n\n\n\n<p><strong>Mise en place ou optimisation du syst\u00e8me d\u2019information<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Participation \u00e0 la mise en place des outils de gestion (d\u00e9finition des flux d&rsquo;information, param\u00e9trage des applications, animation de r\u00e9unions projets concernant les tableaux de bord et l&rsquo;information financi\u00e8re, etc\u2026)<\/li>\n<\/ul>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Qualifications<\/strong><\/h5>\n\n\n\n<ul class=\"wp-block-list\">\n<li>8 ans et + d&rsquo;exp\u00e9rience acquise en contexte international ou en cabinet d\u2019audit comme Manager Audit, Contr\u00f4leur Interne ou Contr\u00f4leur de Gestion<\/li>\n\n\n\n<li>Excellente capacit\u00e9 d&rsquo;autonomie d\u00e9cisionnelle<\/li>\n\n\n\n<li>Ma\u00eetrise de l&rsquo;utilisation des syst\u00e8mes d\u2019information : tableurs, bases de donn\u00e9es, ERP, CRM<\/li>\n\n\n\n<li>Excellente culture comptable et financi\u00e8re en g\u00e9n\u00e9rale<\/li>\n\n\n\n<li>Bonne connaissance du fonctionnement d&rsquo;entreprises technologiques<\/li>\n\n\n\n<li>Comp\u00e9tence en analyse de donn\u00e9es\u00a0<\/li>\n\n\n\n<li>Aisance relationnelle pour dialoguer avec diff\u00e9rents types d\u2019interlocuteurs\u00a0: Finance Managers, comptables mais aussi les op\u00e9rationnels non-financiers, pour collecter l\u2019information<\/li>\n\n\n\n<li>F\u00e9d\u00e9rateur d&rsquo;\u00e9quipe et forte capacit\u00e9 de travail<\/li>\n\n\n\n<li>Capacit\u00e9 d&rsquo;organisation et de planification<\/li>\n\n\n\n<li>Capacit\u00e9 d\u2019anticipation et r\u00e9activit\u00e9 face aux \u00e9volutions \u00e9conomiques pouvant avoir un impact sur l\u2019entreprise<\/li>\n\n\n\n<li>Adaptabilit\u00e9 face \u00e0 l\u2019\u00e9volution r\u00e9guli\u00e8re des technologies et des normes\u00a0financi\u00e8res<\/li>\n\n\n\n<li>Esprit de synth\u00e8se pour conceptualiser rapidement des probl\u00e8mes et leurs solutions\u00a0<\/li>\n\n\n\n<li>Curiosit\u00e9 et esprit critique pour l\u2019analyse des chiffres\u00a0<\/li>\n\n\n\n<li>\u00catre persuasif, savoir faire entendre son point de vue face aux responsables fonctionnels et op\u00e9rationnels.<\/li>\n\n\n\n<li>Parfaite compr\u00e9hension des normes IFRS<\/li>\n\n\n\n<li>Savoir parler Anglais est un gros atout<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A propos du poste Depuis plus de dix ans, RightCom r\u00e9volutionne l\u2019exp\u00e9rience client en Afrique. En cr\u00e9ant des exp\u00e9riences innovantes qui rendent le parcours client fluide, personnalis\u00e9, simple et exceptionnel, RightCom permet aux entreprises dans une trentaine de pays de prosp\u00e9rer dans l\u2019\u00e9conomie de l\u2019exp\u00e9rience. Notre plateforme CX, RightCom XP, permet aux entreprises d\u2019anticiper les [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-15054","rightcom_jobs","type-rightcom_jobs","status-publish","hentry","rightcom_jobs-cat-finances","rightcom_job-loc-ghana-fr","rightcom_job-loc-ivory-coast-cote-divoire-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/rightcom.com\/fr\/wp-json\/wp\/v2\/rightcom_jobs\/15054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rightcom.com\/fr\/wp-json\/wp\/v2\/rightcom_jobs"}],"about":[{"href":"https:\/\/rightcom.com\/fr\/wp-json\/wp\/v2\/types\/rightcom_jobs"}],"wp:attachment":[{"href":"https:\/\/rightcom.com\/fr\/wp-json\/wp\/v2\/media?parent=15054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}